{"id":171719,"date":"2024-06-04T09:25:15","date_gmt":"2024-06-04T13:25:15","guid":{"rendered":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification-3\/"},"modified":"2026-09-02T00:16:42","modified_gmt":"2026-09-02T04:16:42","slug":"change-management-foundation-and-practitioner-certification","status":"publish","type":"product","link":"https:\/\/dev-corporate.algonquincollege.com\/fr\/produit\/change-management-foundation-and-practitioner-certification\/","title":{"rendered":"Change Management Foundation and Practitioner Certification"},"content":{"rendered":"<p>Dealing effectively with change is a high priority for organizations today. The APMG-International Change Management\u2122 Certification has been developed by APMG in partnership with the Change Management Institute (CMI), an independent, global professional association of change managers. They have developed a professional \u2018body of knowledge\u00a0\u00bb for the discipline of change management, which provides an independent benchmark for the professional knowledge expected of an effective change manager.<\/p>\n<p>Change Management Foundation and Practitioner levels present the latest knowledge theory and best practices in effective change management along with professional certification.<\/p>\n<p><strong>How Your Organization Will Benefit:<\/strong><\/p>\n<ul>\n<li>Build the organization&rsquo;s capability and capacity to deal successfully with change, improving agility.<\/li>\n<li>Minimize risks associated with failed initiatives.<\/li>\n<li>Develop and sustain employee commitment and alignment with organizational purpose during times of change.<\/li>\n<li>Build and maintain the engagement of internal and external stakeholders with new initiatives.<\/li>\n<li>Improve assessment of change impact, integrated change planning and successful embedding of change into the life of the organization.<\/li>\n<\/ul>\n<p>Participants should expect two hours of study per evening.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Learn the professional knowledge expected of an effective change manager.<\/p>\n","protected":false},"featured_media":182114,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[19,35],"product_tag":[],"class_list":["post-171719","product","type-product","status-publish","has-post-thumbnail","product_cat-all-courses","product_cat-change-management","course_group-certifications-accreditations","course_group-change-management","course_group-change-management-certification","first","instock","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Change Management Foundation and Practitioner Certification - Professional Training - Algonquin College<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Change Management Foundation and Practitioner Certification - Professional Training - Algonquin College\" \/>\n<meta property=\"og:description\" content=\"Learn the professional knowledge expected of an effective change manager.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/\" \/>\n<meta property=\"og:site_name\" content=\"Professional Training - Algonquin College\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T04:16:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev-corporate.algonquincollege.com\/wp-content\/uploads\/2026\/03\/Change-Management.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/\",\"url\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/\",\"name\":\"Change Management Foundation and Practitioner Certification - Professional Training - Algonquin College\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Change-Management.jpg\",\"datePublished\":\"2024-06-04T13:25:15+00:00\",\"dateModified\":\"2026-09-02T04:16:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Change-Management.jpg\",\"contentUrl\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Change-Management.jpg\",\"width\":1400,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/product\\\/change-management-foundation-and-practitioner-certification\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Change Management Foundation and Practitioner Certification\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/#website\",\"url\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/\",\"name\":\"Professional Training - Algonquin College\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/#organization\",\"name\":\"Professional Training - Algonquin College\",\"url\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-acct_logo.png\",\"contentUrl\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-acct_logo.png\",\"width\":300,\"height\":44,\"caption\":\"Professional Training - Algonquin College\"},\"image\":{\"@id\":\"https:\\\/\\\/dev-corporate.algonquincollege.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Change Management Foundation and Practitioner Certification - Professional Training - Algonquin College","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Change Management Foundation and Practitioner Certification - Professional Training - Algonquin College","og_description":"Learn the professional knowledge expected of an effective change manager.","og_url":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/","og_site_name":"Professional Training - Algonquin College","article_modified_time":"2026-09-02T04:16:42+00:00","og_image":[{"width":1400,"height":800,"url":"https:\/\/dev-corporate.algonquincollege.com\/wp-content\/uploads\/2026\/03\/Change-Management.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/","url":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/","name":"Change Management Foundation and Practitioner Certification - Professional Training - Algonquin College","isPartOf":{"@id":"https:\/\/dev-corporate.algonquincollege.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/#primaryimage"},"image":{"@id":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/#primaryimage"},"thumbnailUrl":"https:\/\/dev-corporate.algonquincollege.com\/wp-content\/uploads\/2026\/03\/Change-Management.jpg","datePublished":"2024-06-04T13:25:15+00:00","dateModified":"2026-09-02T04:16:42+00:00","breadcrumb":{"@id":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/#primaryimage","url":"https:\/\/dev-corporate.algonquincollege.com\/wp-content\/uploads\/2026\/03\/Change-Management.jpg","contentUrl":"https:\/\/dev-corporate.algonquincollege.com\/wp-content\/uploads\/2026\/03\/Change-Management.jpg","width":1400,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/dev-corporate.algonquincollege.com\/product\/change-management-foundation-and-practitioner-certification\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev-corporate.algonquincollege.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/dev-corporate.algonquincollege.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Change Management Foundation and Practitioner Certification"}]},{"@type":"WebSite","@id":"https:\/\/dev-corporate.algonquincollege.com\/#website","url":"https:\/\/dev-corporate.algonquincollege.com\/","name":"Professional Training - Algonquin College","description":"","publisher":{"@id":"https:\/\/dev-corporate.algonquincollege.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev-corporate.algonquincollege.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev-corporate.algonquincollege.com\/#organization","name":"Professional Training - Algonquin College","url":"https:\/\/dev-corporate.algonquincollege.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev-corporate.algonquincollege.com\/#\/schema\/logo\/image\/","url":"https:\/\/dev-corporate.algonquincollege.com\/wp-content\/uploads\/2023\/10\/cropped-acct_logo.png","contentUrl":"https:\/\/dev-corporate.algonquincollege.com\/wp-content\/uploads\/2023\/10\/cropped-acct_logo.png","width":300,"height":44,"caption":"Professional Training - Algonquin College"},"image":{"@id":"https:\/\/dev-corporate.algonquincollege.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/product\/171719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/media\/182114"}],"wp:attachment":[{"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/media?parent=171719"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/product_brand?post=171719"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/product_cat?post=171719"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev-corporate.algonquincollege.com\/fr\/wp-json\/wp\/v2\/product_tag?post=171719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}